{"id":2421,"count":3,"description":"","link":"https:\/\/www.vidio.com\/blog\/topic\/scandal-2\/","name":"Scandal 2","slug":"scandal-2","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.vidio.com\/blog\/wp-json\/wp\/v2\/tags\/2421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vidio.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.vidio.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.vidio.com\/blog\/wp-json\/wp\/v2\/posts?tags=2421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}